{"id":526,"date":"2024-04-26T11:43:27","date_gmt":"2024-04-26T14:43:27","guid":{"rendered":"https:\/\/www.comercialvitorialtda.com.br\/loja\/?post_type=product&#038;p=526"},"modified":"2024-04-26T11:43:29","modified_gmt":"2024-04-26T14:43:29","slug":"gondola-central-140-alt-com-ponta","status":"publish","type":"product","link":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/","title":{"rendered":"G\u00f4ndola central 140 alt com ponta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":527,"template":"","meta":[],"product_cat":[37],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>G\u00f4ndola central 140 alt com ponta - Comercial Vit\u00f3ria LTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G\u00f4ndola central 140 alt com ponta - Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/\" \/>\n<meta property=\"og:site_name\" content=\"Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T14:43:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2024\/04\/gondola-central-140-alt-com-ponta.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/\",\"name\":\"G\u00f4ndola central 140 alt com ponta - Comercial Vit\u00f3ria LTDA\",\"isPartOf\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\"},\"datePublished\":\"2024-04-26T14:43:27+00:00\",\"dateModified\":\"2024-04-26T14:43:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"G\u00f4ndola central 140 alt com ponta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"name\":\"Comercial Vit\u00f3ria LTDA\",\"description\":\"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial\",\"publisher\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\",\"name\":\"Comercial Vit\u00f3ria\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"contentUrl\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"width\":225,\"height\":50,\"caption\":\"Comercial Vit\u00f3ria\"},\"image\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G\u00f4ndola central 140 alt com ponta - Comercial Vit\u00f3ria LTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/","og_locale":"pt_BR","og_type":"article","og_title":"G\u00f4ndola central 140 alt com ponta - Comercial Vit\u00f3ria LTDA","og_url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/","og_site_name":"Comercial Vit\u00f3ria LTDA","article_modified_time":"2024-04-26T14:43:29+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2024\/04\/gondola-central-140-alt-com-ponta.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/","name":"G\u00f4ndola central 140 alt com ponta - Comercial Vit\u00f3ria LTDA","isPartOf":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website"},"datePublished":"2024-04-26T14:43:27+00:00","dateModified":"2024-04-26T14:43:29+00:00","breadcrumb":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-140-alt-com-ponta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/"},{"@type":"ListItem","position":3,"name":"G\u00f4ndola central 140 alt com ponta"}]},{"@type":"WebSite","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","name":"Comercial Vit\u00f3ria LTDA","description":"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial","publisher":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization","name":"Comercial Vit\u00f3ria","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/","url":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","contentUrl":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","width":225,"height":50,"caption":"Comercial Vit\u00f3ria"},"image":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product\/526"}],"collection":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media\/527"}],"wp:attachment":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media?parent=526"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=526"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}