{"id":495,"date":"2021-08-06T12:44:28","date_gmt":"2021-08-06T15:44:28","guid":{"rendered":"https:\/\/www.comercialvitorialtda.com.br\/loja\/?post_type=product&#038;p=495"},"modified":"2021-08-06T12:44:28","modified_gmt":"2021-08-06T15:44:28","slug":"montagem-6","status":"publish","type":"product","link":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/","title":{"rendered":"Montagem 6"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":489,"template":"","meta":[],"product_cat":[38],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Montagem 6 - Comercial Vit\u00f3ria LTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montagem 6 - Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/08\/montagem-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/\",\"url\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/\",\"name\":\"Montagem 6 - Comercial Vit\u00f3ria LTDA\",\"isPartOf\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\"},\"datePublished\":\"2021-08-06T15:44:28+00:00\",\"dateModified\":\"2021-08-06T15:44:28+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Montagem 6\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"name\":\"Comercial Vit\u00f3ria LTDA\",\"description\":\"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial\",\"publisher\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\",\"name\":\"Comercial Vit\u00f3ria\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"contentUrl\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"width\":225,\"height\":50,\"caption\":\"Comercial Vit\u00f3ria\"},\"image\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montagem 6 - Comercial Vit\u00f3ria LTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/","og_locale":"pt_BR","og_type":"article","og_title":"Montagem 6 - Comercial Vit\u00f3ria LTDA","og_url":"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/","og_site_name":"Comercial Vit\u00f3ria LTDA","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/08\/montagem-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/","url":"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/","name":"Montagem 6 - Comercial Vit\u00f3ria LTDA","isPartOf":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website"},"datePublished":"2021-08-06T15:44:28+00:00","dateModified":"2021-08-06T15:44:28+00:00","breadcrumb":{"@id":"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/montagem-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/"},{"@type":"ListItem","position":3,"name":"Montagem 6"}]},{"@type":"WebSite","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","name":"Comercial Vit\u00f3ria LTDA","description":"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial","publisher":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization","name":"Comercial Vit\u00f3ria","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/","url":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","contentUrl":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","width":225,"height":50,"caption":"Comercial Vit\u00f3ria"},"image":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product\/495"}],"collection":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media\/489"}],"wp:attachment":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media?parent=495"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=495"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}