{"id":466,"date":"2021-08-05T11:58:14","date_gmt":"2021-08-05T14:58:14","guid":{"rendered":"https:\/\/www.comercialvitorialtda.com.br\/loja\/?post_type=product&#038;p=466"},"modified":"2024-04-24T18:13:33","modified_gmt":"2024-04-24T21:13:33","slug":"gondola-central-1-70","status":"publish","type":"product","link":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/","title":{"rendered":"Gondola Central 1.70"},"content":{"rendered":"<p>gondolas e gondola central na cor branca medindo 1,70 de altura prateleira para mercado pet shop farm\u00e1cia adega &#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>gondolas e gondola central na cor branca medindo 1,70 de altura prateleira para mercado pet shop farm\u00e1cia adega &#8230;.<\/p>\n","protected":false},"featured_media":467,"template":"","meta":[],"product_cat":[37],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gondola Central 1.70 - Comercial Vit\u00f3ria LTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gondola Central 1.70 - Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"og:description\" content=\"gondolas e gondola central na cor branca medindo 1,70 de altura prateleira para mercado pet shop farm\u00e1cia adega &#8230;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/\" \/>\n<meta property=\"og:site_name\" content=\"Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T21:13:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/08\/gondola-central-170.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"583\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/\",\"name\":\"Gondola Central 1.70 - Comercial Vit\u00f3ria LTDA\",\"isPartOf\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\"},\"datePublished\":\"2021-08-05T14:58:14+00:00\",\"dateModified\":\"2024-04-24T21:13:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gondola Central 1.70\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"name\":\"Comercial Vit\u00f3ria LTDA\",\"description\":\"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial\",\"publisher\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\",\"name\":\"Comercial Vit\u00f3ria\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"contentUrl\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"width\":225,\"height\":50,\"caption\":\"Comercial Vit\u00f3ria\"},\"image\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gondola Central 1.70 - Comercial Vit\u00f3ria LTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/","og_locale":"pt_BR","og_type":"article","og_title":"Gondola Central 1.70 - Comercial Vit\u00f3ria LTDA","og_description":"gondolas e gondola central na cor branca medindo 1,70 de altura prateleira para mercado pet shop farm\u00e1cia adega &#8230;.","og_url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/","og_site_name":"Comercial Vit\u00f3ria LTDA","article_modified_time":"2024-04-24T21:13:33+00:00","og_image":[{"width":583,"height":479,"url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/08\/gondola-central-170.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/","name":"Gondola Central 1.70 - Comercial Vit\u00f3ria LTDA","isPartOf":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website"},"datePublished":"2021-08-05T14:58:14+00:00","dateModified":"2024-04-24T21:13:33+00:00","breadcrumb":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/gondola-central-1-70\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/"},{"@type":"ListItem","position":3,"name":"Gondola Central 1.70"}]},{"@type":"WebSite","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","name":"Comercial Vit\u00f3ria LTDA","description":"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial","publisher":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization","name":"Comercial Vit\u00f3ria","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/","url":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","contentUrl":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","width":225,"height":50,"caption":"Comercial Vit\u00f3ria"},"image":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product\/466"}],"collection":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media\/467"}],"wp:attachment":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media?parent=466"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=466"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}