{"id":430,"date":"2021-04-13T09:17:50","date_gmt":"2021-04-13T12:17:50","guid":{"rendered":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/"},"modified":"2021-04-13T09:29:01","modified_gmt":"2021-04-13T12:29:01","slug":"balanca-computadora","status":"publish","type":"product","link":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/","title":{"rendered":"Balan\u00e7a Computadora"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":399,"template":"","meta":[],"product_cat":[24],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Balan\u00e7a Computadora - Comercial Vit\u00f3ria LTDA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Balan\u00e7a Computadora - Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/\" \/>\n<meta property=\"og:site_name\" content=\"Comercial Vit\u00f3ria LTDA\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-13T12:29:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/balanca-computadora.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/\",\"name\":\"Balan\u00e7a Computadora - Comercial Vit\u00f3ria LTDA\",\"isPartOf\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\"},\"datePublished\":\"2021-04-13T12:17:50+00:00\",\"dateModified\":\"2021-04-13T12:29:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Balan\u00e7a Computadora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"name\":\"Comercial Vit\u00f3ria LTDA\",\"description\":\"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial\",\"publisher\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization\",\"name\":\"Comercial Vit\u00f3ria\",\"url\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"contentUrl\":\"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png\",\"width\":225,\"height\":50,\"caption\":\"Comercial Vit\u00f3ria\"},\"image\":{\"@id\":\"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Balan\u00e7a Computadora - Comercial Vit\u00f3ria LTDA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/","og_locale":"pt_BR","og_type":"article","og_title":"Balan\u00e7a Computadora - Comercial Vit\u00f3ria LTDA","og_url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/","og_site_name":"Comercial Vit\u00f3ria LTDA","article_modified_time":"2021-04-13T12:29:01+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/balanca-computadora.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/","name":"Balan\u00e7a Computadora - Comercial Vit\u00f3ria LTDA","isPartOf":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website"},"datePublished":"2021-04-13T12:17:50+00:00","dateModified":"2021-04-13T12:29:01+00:00","breadcrumb":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/produto\/balanca-computadora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/www.comercialvitorialtda.com.br\/loja\/nossos-produtos\/"},{"@type":"ListItem","position":3,"name":"Balan\u00e7a Computadora"}]},{"@type":"WebSite","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#website","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","name":"Comercial Vit\u00f3ria LTDA","description":"Empresa especializada no mercado de refrigera\u00e7\u00e3o comercial","publisher":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comercialvitorialtda.com.br\/loja\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#organization","name":"Comercial Vit\u00f3ria","url":"https:\/\/www.comercialvitorialtda.com.br\/loja\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/","url":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","contentUrl":"http:\/\/www.comercialvitorialtda.com.br\/loja\/wp-content\/uploads\/2021\/04\/logotipo.png","width":225,"height":50,"caption":"Comercial Vit\u00f3ria"},"image":{"@id":"https:\/\/www.comercialvitorialtda.com.br\/loja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product\/430"}],"collection":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media\/399"}],"wp:attachment":[{"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/media?parent=430"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_cat?post=430"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.comercialvitorialtda.com.br\/loja\/wp-json\/wp\/v2\/product_tag?post=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}